{"id":17249,"date":"2026-02-24T16:29:57","date_gmt":"2026-02-24T09:29:57","guid":{"rendered":"https:\/\/14thplan.nesdc.go.th\/?p=17249"},"modified":"2026-03-09T10:42:26","modified_gmt":"2026-03-09T03:42:26","slug":"osm-nakhonpathom","status":"publish","type":"post","link":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/","title":{"rendered":"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"17249\" class=\"elementor elementor-17249\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a11d80c e-con-full e-flex e-con e-parent\" data-id=\"a11d80c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b625ea elementor-widget elementor-widget-spacer\" data-id=\"7b625ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca4d915 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ca4d915\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3a677019 e-flex e-con-boxed e-con e-parent\" data-id=\"3a677019\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-506ba293 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"506ba293\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 24 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569\u00a0<strong>\u0e19\u0e32\u0e22\u0e2d\u0e32\u0e23\u0e35\u0e22\u0e4c \u0e0a\u0e27\u0e25\u0e34\u0e15\u0e0a\u0e35\u0e27\u0e34\u0e19\u0e01\u0e38\u0e25<\/strong>\u00a0\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u00a0<strong>\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e28\u0e28\u0e34\u0e18\u0e23 \u0e1e\u0e25\u0e31\u0e15\u0e16\u0e40\u0e14\u0e0a<\/strong>\u00a0\u0e23\u0e2d\u0e07\u0e40\u0e25\u0e02\u0e32\u0e18\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e20\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e32\u0e23\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34\u00a0<strong>\u0e23\u0e28.\u0e14\u0e23.\u0e1b\u0e31\u0e17\u0e21\u0e32\u0e27\u0e14\u0e35 \u0e42\u0e1e\u0e0a\u0e19\u0e38\u0e01\u0e39\u0e25<\/strong>\u00a0\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e16\u0e48\u0e32\u0e22\u0e17\u0e2d\u0e14\u0e41\u0e25\u0e30\u0e25\u0e07\u0e17\u0e38\u0e19\u0e43\u0e19\u0e27\u0e34\u0e08\u0e31\u0e22 \u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u00a0<strong>\u0e19\u0e32\u0e22\u0e2a\u0e38\u0e23\u0e23\u0e31\u0e10 \u0e40\u0e19\u0e35\u0e22\u0e21\u0e01\u0e25\u0e32\u0e07<\/strong>\u00a0\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e14\u0e49\u0e32\u0e19\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19 \u0e41\u0e25\u0e30<b>\u0e19\u0e32\u0e22\u0e2d\u0e18\u0e34\u0e1e\u0e07\u0e28\u0e4c \u0e2b\u0e34\u0e23\u0e31\u0e0d\u0e40\u0e23\u0e37\u0e2d\u0e07\u0e42\u0e0a\u0e04<\/b>\u00a0\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e01\u0e2d\u0e07\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e2a\u0e28\u0e0a. \u0e40\u0e1b\u0e34\u0e14\u0e40\u0e27\u0e17\u0e35\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e41\u0e25\u0e30\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e43\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 (\u0e19\u0e19\u0e17\u0e1a\u0e38\u0e23\u0e35 \u0e2a\u0e21\u0e38\u0e17\u0e23\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23 \u0e1b\u0e17\u0e38\u0e21\u0e18\u0e32\u0e19\u0e35 \u0e41\u0e25\u0e30\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21) \u0e13 \u0e42\u0e23\u0e07\u0e41\u0e23\u0e21 \u0e44\u0e21\u0e14\u0e49\u0e32 \u0e41\u0e01\u0e23\u0e19\u0e14\u0e4c \u0e17\u0e27\u0e32\u0e23\u0e27\u0e14\u0e35 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21<\/p><p>\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e21\u0e35\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e32\u0e19\u0e42\u0e04\u0e23\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e10\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e43\u0e19\u0e21\u0e34\u0e15\u0e34\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e32\u0e19\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e25\u0e08\u0e34\u0e2a\u0e15\u0e34\u0e01\u0e2a\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e15\u0e48\u0e2d\u0e01\u0e31\u0e1a\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19 \u0e17\u0e48\u0e32\u0e40\u0e23\u0e37\u0e2d \u0e41\u0e25\u0e30 \u0e19\u0e34\u0e04\u0e21\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e40\u0e0a\u0e34\u0e07\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49 5 \u0e40\u0e2a\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e33\u0e04\u0e31\u0e0d \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08 \u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e17\u0e38\u0e19\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21<\/p><p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19 \u0e02\u0e49\u0e2d\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e30 \u0e41\u0e25\u0e30\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e15\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e15\u0e2d\u0e1a\u0e17\u0e35\u0e48\u0e14\u0e35\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e27\u0e48\u0e32 150 \u0e04\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e08\u0e32\u0e01\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e20\u0e32\u0e04\u0e2a\u0e48\u0e27\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e01\u0e32\u0e23\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e20\u0e32\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1c\u0e39\u0e49\u0e40\u0e1b\u0e23\u0e32\u0e30\u0e1a\u0e32\u0e07 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e04\u0e32\u0e14\u0e2b\u0e27\u0e31\u0e07\u0e27\u0e48\u0e32\u0e23\u0e48\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e43\u0e2b\u0e21\u0e48 \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1c\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e07\u0e48\u0e32\u0e22 \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e14\u0e49\u0e08\u0e23\u0e34\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07 \u0e21\u0e35\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e1b\u0e25\u0e07\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e39\u0e1b\u0e18\u0e23\u0e23\u0e21 \u0e41\u0e25\u0e30\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e44\u0e1b\u0e2a\u0e39\u0e48\u0e17\u0e38\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e04\u0e19\u0e41\u0e25\u0e30\u0e17\u0e38\u0e01\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e31\u0e48\u0e27\u0e16\u0e36\u0e07<\/p><p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 25 \u0e01\u0e38\u0e21\u0e20\u0e32\u0e1e\u0e31\u0e19\u0e18\u0e4c 2569 \u0e2a\u0e28\u0e0a. \u0e44\u0e14\u0e49\u0e08\u0e31\u0e14\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e08\u0e32\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\/\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u0e13 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e08\u0e32\u0e01 \u0e2a\u0e28\u0e0a. \u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e42\u0e14\u0e22\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27\u0e44\u0e14\u0e49\u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e41\u0e2a\u0e14\u0e07\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e21\u0e15\u0e34 (Role Play) \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e1a\u0e39\u0e18\u0e19\u0e34\u0e17\u0e23\u0e23\u0e28\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e38\u0e1b\u0e2a\u0e32\u0e23\u0e30\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e02\u0e2d\u0e07\u0e41\u0e15\u0e48\u0e25\u0e30\u0e40\u0e2a\u0e32\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e2a\u0e19\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e23\u0e48\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e2f \u0e41\u0e25\u0e30\u0e14\u0e36\u0e07\u0e14\u0e39\u0e14\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e02\u0e2d\u0e07\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19\u0e44\u0e14\u0e49\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e41\u0e25\u0e30\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f<br \/>\u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e15\u0e47\u0e21\u0e17\u0e35\u0e48 \u0e42\u0e14\u0e22\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e21\u0e35\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\/\u0e19\u0e31\u0e01\u0e28\u0e36\u0e01\u0e29\u0e32\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e23\u0e32\u0e0a\u0e20\u0e31\u0e0f\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e1e\u0e38\u0e17\u0e18\u0e21\u0e13\u0e11\u0e25 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e28\u0e36\u0e01\u0e29\u0e32\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 \u0e41\u0e25\u0e30\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e04\u0e23\u0e34\u0e2a\u0e40\u0e15\u0e35\u0e22\u0e19\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e27\u0e48\u0e32 150 \u0e04\u0e19<br \/><br \/><\/p><p>\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e20\u0e32\u0e1e\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u00a0<a href=\"https:\/\/drive.google.com\/drive\/folders\/1lGyILITILLUQkSs3gWkCbt2cmVlbnSKn?usp=sharing\" target=\"_blank\" rel=\"noopener\">https:\/\/drive.google.com\/drive\/folders\/1lGyILITILLUQkSs3gWkCbt2cmVlbnSKn?usp=sharing<\/a><\/p><hr \/><p>\u0e02\u0e48\u0e32\u0e27 : \u0e01\u0e2d\u0e07\u0e22\u0e38\u0e17\u0e18\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e02\u0e35\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07\u0e02\u0e31\u0e19 (\u0e01\u0e1e\u0e02.)<br \/>\u0e20\u0e32\u0e1e : \u0e40\u0e21\u0e10\u0e15\u0e34\u0e0d\u0e32 \u0e27\u0e07\u0e29\u0e4c\u0e20\u0e31\u0e01\u0e14\u0e35<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-63d169b e-flex e-con-boxed e-con e-parent\" data-id=\"63d169b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d09e041 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"d09e041\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8071-1-scaled-1.jpg\" alt=\"7W5A8071-1-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8522-scaled-1.jpg\" alt=\"7W5A8522-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/\u0e41\u0e1c\u0e19\u0e2f-14-\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png\" alt=\"\u0e41\u0e1c\u0e19\u0e2f-14-\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8090-scaled-1.jpg\" alt=\"7W5A8090-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8230-scaled-1.jpg\" alt=\"7W5A8230-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8261-scaled-1.jpg\" alt=\"7W5A8261-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8389-scaled-1.jpg\" alt=\"7W5A8389-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8370-scaled-1.jpg\" alt=\"7W5A8370-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8414-scaled-1.jpg\" alt=\"7W5A8414-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A9035-scaled-1.jpg\" alt=\"7W5A9035-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8987-scaled-1.jpg\" alt=\"7W5A8987-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8918-scaled-1.jpg\" alt=\"7W5A8918-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8844-scaled-1.jpg\" alt=\"7W5A8844-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8746-scaled-1.jpg\" alt=\"7W5A8746-scaled\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 15\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/7W5A8627-scaled-1.jpg\" alt=\"7W5A8627-scaled\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc6eead elementor-widget elementor-widget-spacer\" data-id=\"dc6eead\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17265,"comment_status":"closed","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[38],"tags":[],"class_list":["post-17249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-osm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/\" \/>\r\n<meta property=\"og:locale\" content=\"th_TH\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\" \/>\r\n<meta property=\"og:description\" content=\"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31 [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/\" \/>\r\n<meta property=\"og:site_name\" content=\"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\" \/>\r\n<meta property=\"article:published_time\" content=\"2026-02-24T09:29:57+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-03-09T03:42:26+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\r\n\t<meta property=\"og:image:height\" content=\"720\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"admin\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#\\\/schema\\\/person\\\/8e7c896271f6614483679b1044bec16f\"},\"headline\":\"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\",\"datePublished\":\"2026-02-24T09:29:57+00:00\",\"dateModified\":\"2026-03-09T03:42:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/\"},\"wordCount\":14,\"publisher\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png\",\"articleSection\":[\"\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e2f 14\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/\",\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/\",\"name\":\"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png\",\"datePublished\":\"2026-02-24T09:29:57+00:00\",\"dateModified\":\"2026-03-09T03:42:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/#primaryimage\",\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png\",\"contentUrl\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/osm-nakhonpathom\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#website\",\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/\",\"name\":\"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\",\"description\":\"\u0e40\u0e23\u0e32\u0e04\u0e34\u0e14 \u0e40\u0e23\u0e32\u0e40\u0e2b\u0e47\u0e19 \u0e40\u0e23\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49\",\"publisher\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#organization\",\"name\":\"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\",\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-page.png\",\"contentUrl\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-page.png\",\"width\":512,\"height\":512,\"caption\":\"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\"},\"image\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#\\\/schema\\\/person\\\/8e7c896271f6614483679b1044bec16f\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/151e0c41be8911af94e58dedcdaf6f8ca1ec72f8d19e56c303cc4d8b501f6716?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/151e0c41be8911af94e58dedcdaf6f8ca1ec72f8d19e56c303cc4d8b501f6716?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/151e0c41be8911af94e58dedcdaf6f8ca1ec72f8d19e56c303cc4d8b501f6716?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\\\/\\\/14thplan.nesdc.go.th\"],\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/author\\\/admin\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","og_description":"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31 [&hellip;]","og_url":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/","og_site_name":"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","article_published_time":"2026-02-24T09:29:57+00:00","article_modified_time":"2026-03-09T03:42:26+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/#article","isPartOf":{"@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/"},"author":{"name":"admin","@id":"https:\/\/14thplan.nesdc.go.th\/#\/schema\/person\/8e7c896271f6614483679b1044bec16f"},"headline":"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21","datePublished":"2026-02-24T09:29:57+00:00","dateModified":"2026-03-09T03:42:26+00:00","mainEntityOfPage":{"@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/"},"wordCount":14,"publisher":{"@id":"https:\/\/14thplan.nesdc.go.th\/#organization"},"image":{"@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/#primaryimage"},"thumbnailUrl":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png","articleSection":["\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e2f 14"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/","url":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/","name":"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","isPartOf":{"@id":"https:\/\/14thplan.nesdc.go.th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/#primaryimage"},"image":{"@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/#primaryimage"},"thumbnailUrl":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png","datePublished":"2026-02-24T09:29:57+00:00","dateModified":"2026-03-09T03:42:26+00:00","breadcrumb":{"@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/#primaryimage","url":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png","contentUrl":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/03\/\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21.png","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/osm-nakhonpathom\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/14thplan.nesdc.go.th\/"},{"@type":"ListItem","position":2,"name":"\u0e2a\u0e28\u0e0a. \u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e04\u0e27\u0e32\u0e21\u0e04\u0e34\u0e14\u0e40\u0e2b\u0e47\u0e19\u0e15\u0e48\u0e2d\u0e23\u0e48\u0e32\u0e07\u0e01\u0e23\u0e2d\u0e1a\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14 \u0e01\u0e25\u0e38\u0e48\u0e21\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e20\u0e32\u0e04\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e34\u0e21\u0e13\u0e11\u0e25 \u0e13 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e19\u0e04\u0e23\u0e1b\u0e10\u0e21"}]},{"@type":"WebSite","@id":"https:\/\/14thplan.nesdc.go.th\/#website","url":"https:\/\/14thplan.nesdc.go.th\/","name":"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","description":"\u0e40\u0e23\u0e32\u0e04\u0e34\u0e14 \u0e40\u0e23\u0e32\u0e40\u0e2b\u0e47\u0e19 \u0e40\u0e23\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49","publisher":{"@id":"https:\/\/14thplan.nesdc.go.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/14thplan.nesdc.go.th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/14thplan.nesdc.go.th\/#organization","name":"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","url":"https:\/\/14thplan.nesdc.go.th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/14thplan.nesdc.go.th\/#\/schema\/logo\/image\/","url":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/06\/logo-page.png","contentUrl":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/06\/logo-page.png","width":512,"height":512,"caption":"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!"},"image":{"@id":"https:\/\/14thplan.nesdc.go.th\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/14thplan.nesdc.go.th\/#\/schema\/person\/8e7c896271f6614483679b1044bec16f","name":"admin","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/secure.gravatar.com\/avatar\/151e0c41be8911af94e58dedcdaf6f8ca1ec72f8d19e56c303cc4d8b501f6716?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/151e0c41be8911af94e58dedcdaf6f8ca1ec72f8d19e56c303cc4d8b501f6716?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/151e0c41be8911af94e58dedcdaf6f8ca1ec72f8d19e56c303cc4d8b501f6716?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/14thplan.nesdc.go.th"],"url":"https:\/\/14thplan.nesdc.go.th\/index.php\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/posts\/17249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/comments?post=17249"}],"version-history":[{"count":6,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/posts\/17249\/revisions"}],"predecessor-version":[{"id":17282,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/posts\/17249\/revisions\/17282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/media\/17265"}],"wp:attachment":[{"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/media?parent=17249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/categories?post=17249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/tags?post=17249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}