{"id":186,"date":"2025-02-21T09:25:49","date_gmt":"2025-02-21T02:25:49","guid":{"rendered":"https:\/\/14thplan.nesdc.go.th\/?page_id=186"},"modified":"2026-07-10T17:09:03","modified_gmt":"2026-07-10T10:09:03","slug":"progress","status":"publish","type":"page","link":"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/","title":{"rendered":"\u0e01\u0e49\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19 14"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"186\" class=\"elementor elementor-186\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b11bfe7 e-flex e-con-boxed e-con e-parent\" data-id=\"b11bfe7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb8a280 elementor-widget-tablet__width-initial elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"fb8a280\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"98\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/11\/heading.png\" class=\"attachment-medium_large size-medium_large wp-image-16456\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-34a5e8f e-con-full e-flex e-con e-parent\" data-id=\"34a5e8f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f82e5f elementor-widget elementor-widget-image\" data-id=\"5f82e5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"93\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/03\/Main-Headline-1-1024x148.png\" class=\"attachment-large size-large wp-image-1225\" alt=\"\" srcset=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/03\/Main-Headline-1-1024x148.png 1024w, https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/03\/Main-Headline-1-300x43.png 300w, https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/03\/Main-Headline-1-768x111.png 768w, https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/03\/Main-Headline-1-1536x222.png 1536w, https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/03\/Main-Headline-1-2048x297.png 2048w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1a41f7d elementor-widget elementor-widget-text-editor\" data-id=\"1a41f7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14<br \/>(\u0e1e.\u0e28. 2571 &#8211; 2575)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8f1a6b elementor-widget elementor-widget-image\" data-id=\"d8f1a6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"4000\" height=\"2250\" src=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2026\/07\/\u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e15\u0e48\u0e2d\u0e44\u0e1b.jpg\" class=\"attachment-full size-full wp-image-17914\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14(\u0e1e.\u0e28. 2571 &#038;#82 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-186","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>\u0e01\u0e49\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19 14 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/\" \/>\r\n<meta property=\"og:locale\" content=\"th_TH\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"\u0e01\u0e49\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19 14 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\" \/>\r\n<meta property=\"og:description\" content=\"\u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14(\u0e1e.\u0e28. 2571 &amp;#82 [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/\" \/>\r\n<meta property=\"og:site_name\" content=\"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-07-10T10:09:03+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/11\/heading.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\r\n\t<meta property=\"og:image:height\" content=\"153\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/progress\\\/\",\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/progress\\\/\",\"name\":\"\u0e01\u0e49\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19 14 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/progress\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/progress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/heading.png\",\"datePublished\":\"2025-02-21T02:25:49+00:00\",\"dateModified\":\"2026-07-10T10:09:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/progress\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/progress\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/progress\\\/#primaryimage\",\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/heading.png\",\"contentUrl\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/heading.png\",\"width\":1000,\"height\":153},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/index.php\\\/progress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e01\u0e49\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#website\",\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/\",\"name\":\"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\",\"description\":\"\u0e40\u0e23\u0e32\u0e04\u0e34\u0e14 \u0e40\u0e23\u0e32\u0e40\u0e2b\u0e47\u0e19 \u0e40\u0e23\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49\",\"publisher\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#organization\",\"name\":\"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\",\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-page.png\",\"contentUrl\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/logo-page.png\",\"width\":512,\"height\":512,\"caption\":\"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!\"},\"image\":{\"@id\":\"https:\\\/\\\/14thplan.nesdc.go.th\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e01\u0e49\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19 14 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e01\u0e49\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19 14 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","og_description":"\u0e01\u0e23\u0e2d\u0e1a\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e17\u0e33\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2f \u0e09\u0e1a\u0e31\u0e1a\u0e17\u0e35\u0e48 14(\u0e1e.\u0e28. 2571 &#82 [&hellip;]","og_url":"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/","og_site_name":"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","article_modified_time":"2026-07-10T10:09:03+00:00","og_image":[{"width":1000,"height":153,"url":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/11\/heading.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/","url":"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/","name":"\u0e01\u0e49\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19 14 - \u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","isPartOf":{"@id":"https:\/\/14thplan.nesdc.go.th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/#primaryimage"},"image":{"@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/#primaryimage"},"thumbnailUrl":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/11\/heading.png","datePublished":"2025-02-21T02:25:49+00:00","dateModified":"2026-07-10T10:09:03+00:00","breadcrumb":{"@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/#primaryimage","url":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/11\/heading.png","contentUrl":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/11\/heading.png","width":1000,"height":153},{"@type":"BreadcrumbList","@id":"https:\/\/14thplan.nesdc.go.th\/index.php\/progress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/14thplan.nesdc.go.th\/"},{"@type":"ListItem","position":2,"name":"\u0e01\u0e49\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e2d\u0e07\u0e41\u0e1c\u0e19 14"}]},{"@type":"WebSite","@id":"https:\/\/14thplan.nesdc.go.th\/#website","url":"https:\/\/14thplan.nesdc.go.th\/","name":"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","description":"\u0e40\u0e23\u0e32\u0e04\u0e34\u0e14 \u0e40\u0e23\u0e32\u0e40\u0e2b\u0e47\u0e19 \u0e40\u0e23\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49","publisher":{"@id":"https:\/\/14thplan.nesdc.go.th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/14thplan.nesdc.go.th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/14thplan.nesdc.go.th\/#organization","name":"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!","url":"https:\/\/14thplan.nesdc.go.th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/14thplan.nesdc.go.th\/#\/schema\/logo\/image\/","url":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/06\/logo-page.png","contentUrl":"https:\/\/14thplan.nesdc.go.th\/wp-content\/uploads\/2025\/06\/logo-page.png","width":512,"height":512,"caption":"\u0e41\u0e1c\u0e19 14 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e1b\u0e15\u0e48\u0e2d!"},"image":{"@id":"https:\/\/14thplan.nesdc.go.th\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/pages\/186","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/comments?post=186"}],"version-history":[{"count":168,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/pages\/186\/revisions"}],"predecessor-version":[{"id":17920,"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/pages\/186\/revisions\/17920"}],"wp:attachment":[{"href":"https:\/\/14thplan.nesdc.go.th\/index.php\/wp-json\/wp\/v2\/media?parent=186"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}